{"id":8761,"date":"2026-05-12T12:52:42","date_gmt":"2026-05-12T19:52:42","guid":{"rendered":"https:\/\/matutino1179.com\/?p=8761"},"modified":"2026-05-12T12:52:43","modified_gmt":"2026-05-12T19:52:43","slug":"inician-jornada-de-descacharre-en-yavaros-para-combatir-el-dengue","status":"publish","type":"post","link":"https:\/\/matutino1179.com\/index.php\/2026\/05\/12\/inician-jornada-de-descacharre-en-yavaros-para-combatir-el-dengue\/","title":{"rendered":"\u00a1Inician jornada de descacharre en Yavaros para combatir el dengue!"},"content":{"rendered":"<h5>Autoridades municipales pusieron en marcha una jornada de descacharre en el puerto de Yavaros como parte de las acciones preventivas para combatir el dengue y reducir la presencia de criaderos de mosquitos en la comunidad.<\/h5>\n<hr \/>\n<p>Con estas labores se busca reforzar la limpieza de espacios p\u00fablicos y hogares, adem\u00e1s de disminuir riesgos para la salud de las familias del municipio. Las autoridades destacaron que mantener patios y calles libres de objetos en desuso ayuda a prevenir la proliferaci\u00f3n del mosquito transmisor.<\/p>\n<p>Asimismo, se invit\u00f3 a la ciudadan\u00eda a participar activamente sacando cacharros y art\u00edculos que ya no utilicen, resaltando que la colaboraci\u00f3n de la poblaci\u00f3n es clave para mantener colonias m\u00e1s limpias y seguras.<\/p>\n<p>Gobierno de Huatabampo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades municipales pusieron en marcha una jornada de descacharre en el puerto de Yavaros como parte de las<\/p>\n","protected":false},"author":1,"featured_media":8762,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local_id"],"_links":{"self":[{"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/posts\/8761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/comments?post=8761"}],"version-history":[{"count":1,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/posts\/8761\/revisions"}],"predecessor-version":[{"id":8763,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/posts\/8761\/revisions\/8763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/media\/8762"}],"wp:attachment":[{"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/media?parent=8761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/categories?post=8761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matutino1179.com\/index.php\/wp-json\/wp\/v2\/tags?post=8761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}